{"id":10236,"date":"2011-09-24T14:54:47","date_gmt":"2011-09-24T13:54:47","guid":{"rendered":"http:\/\/www.bohnenzeitung.com\/?p=10236"},"modified":"2011-09-24T14:54:47","modified_gmt":"2011-09-24T13:54:47","slug":"ein-jahr-feuerlilie-2","status":"publish","type":"post","link":"https:\/\/www.bohnenzeitung.com\/wp\/ein-jahr-feuerlilie-2\/","title":{"rendered":"Ein Jahr&#8230; &#8211; Gedankensplitter"},"content":{"rendered":"<p>Die Sonne geht unter.<br \/>\nEin sch\u00f6ner Herbsttag.<br \/>\nZu Ende.<br \/>\nEin wenig Nebel in der Fr\u00fch.<br \/>\nAber die Sonne.<br \/>\nSie zauberte.<br \/>\nGold ins Land.<br \/>\nMan atmet.<br \/>\nDie w\u00fcrzige Luft.<br \/>\nSammelt.<br \/>\nBunte Bl\u00e4tter.<br \/>\nN\u00fcsse.<br \/>\nKastanien.<br \/>\nBeeren\u2026<br \/>\nUnd genie\u00dft.<br \/>\nDas Leben\u2026<br \/>\nDer Tag.<br \/>\nEr neigt sich.<br \/>\nBald wird es dunkel sein.<br \/>\nDie Katze g\u00e4hnt.<br \/>\nDann schl\u00e4ft sie weiter\u2026<\/p>\n<p>Ich stehe am Fenster.<br \/>\nSchiebe den Vorhang zur\u00fcck.<br \/>\nManches.<br \/>\nGleicht dem Vorjahr.<br \/>\nUnd doch.<br \/>\nIst alles anders.<br \/>\nGanz anders.<br \/>\nAls vor einem Jahr.<br \/>\nWenn ich zur\u00fcck denke.<br \/>\nVerbittere ich noch immer.<br \/>\nOb des Unrechts.<br \/>\nOb des Missbrauchs.<br \/>\nSpielball.<br \/>\nDer ich war.<br \/>\nSo lange Zeit.<br \/>\nSo lange ausgeliefert.<br \/>\nIch schluckte.<br \/>\nTag f\u00fcr Tag.<br \/>\nVerbale Pr\u00fcgel.<br \/>\nWann immer es m\u00f6glich war.<br \/>\nBis es zu viel wurde.<br \/>\nKnapp vor dem Zusammenbruch.<br \/>\nAls es nicht mehr ging.<br \/>\nEin letztes Ausb\u00e4umen.<br \/>\nEs f\u00fchrte mich.<br \/>\nAus der Misere.<br \/>\nIn ein neues Leben\u2026<br \/>\nIch lasse den Vorhang los.<br \/>\nTrete weg.<br \/>\nVom Fenster.<br \/>\nNein.<br \/>\nJetzt.<br \/>\nBin ich nicht.<br \/>\nIm Paradies.<br \/>\nGewiss nicht.<br \/>\nAber hier.<br \/>\nKann ich wieder Mensch sein.<br \/>\nHier ist Leben\u2026<\/p>\n<p>Ich l\u00e4chle still.<br \/>\nJa.<br \/>\nManchmal.<br \/>\nDa sp\u00fcre ich das Gef\u00fchl.<br \/>\nIn meinem Innersten.<br \/>\nSo ein leises Gl\u00fcck.<br \/>\nSo wie fr\u00fcher.<br \/>\nAls ich noch jung war.<br \/>\nEtwas weniger zerzaust.<br \/>\nUnd menschenfreundlicher.<br \/>\nEs ist wieder da.<br \/>\nNachdem es tot schien.<br \/>\nVerschwunden.<br \/>\nVerpufft im Leid.<br \/>\nDurch L\u00fcge und Intrige.<br \/>\nUnd durch tiefe B\u00f6sartigkeit\u2026<br \/>\nEs ist vorbei.<br \/>\nSagen mir Leute.<br \/>\nDie es gut meinen.<br \/>\nMit mir.<br \/>\nEs ist vorbei.<br \/>\nUnd wird es doch nie sein.<br \/>\nAuch wenn das Gl\u00fccksgef\u00fchl.<br \/>\nSich wieder einstellt.<br \/>\nAn manchen Tagen.<br \/>\nLebensfreude.<br \/>\nUnd auch mehr.<br \/>\nFreude.<br \/>\nDas es ist.<br \/>\nWie es ist\u2026<br \/>\nEs ist vorbei.<br \/>\nUnd doch auch nicht.<br \/>\nDer Vorhang fiel.<br \/>\nVor einem Jahr.<br \/>\nEin Trauerspiel.<br \/>\nGing zu Ende.<br \/>\nEs macht wieder Freude zu leben\u2026<\/p>\n<p>Vivienne\/Gedankensplitter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sonne geht unter. Ein sch&ouml;ner Herbsttag. Zu Ende. Ein wenig Nebel in der Fr&uuml;h. Aber die Sonne. Sie zauberte. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Ein Jahr&#8230; &#8211; Gedankensplitter\" class=\"read-more button\" href=\"https:\/\/www.bohnenzeitung.com\/wp\/ein-jahr-feuerlilie-2\/#more-10236\" aria-label=\"Mehr Informationen \u00fcber Ein Jahr&#8230; &#8211; Gedankensplitter\">Weiter<\/a><\/p>\n","protected":false},"author":1,"featured_media":28639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-10236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gedankensplitter","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/10236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/comments?post=10236"}],"version-history":[{"count":0,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/10236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media\/28639"}],"wp:attachment":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media?parent=10236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/categories?post=10236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/tags?post=10236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}