{"id":23003,"date":"2017-04-09T08:20:46","date_gmt":"2017-04-09T06:20:46","guid":{"rendered":"http:\/\/www.bohnenzeitung.com\/?p=23003"},"modified":"2018-10-02T13:57:52","modified_gmt":"2018-10-02T11:57:52","slug":"flexiblere-arbeitszeiten-ist-das-fuer-euch-vorstellbar-umfrageeergebnis","status":"publish","type":"post","link":"https:\/\/www.bohnenzeitung.com\/wp\/flexiblere-arbeitszeiten-ist-das-fuer-euch-vorstellbar-umfrageeergebnis\/","title":{"rendered":"Flexiblere Arbeitszeiten &#8211; ist das f\u00fcr euch vorstellbar? &#8211; Umfrageeergebnis"},"content":{"rendered":"<p><div id=\"polls-105\" class=\"wp-polls\">\n\t\t<p style=\"text-align: center;\"><strong>Flexiblere Arbeitszeiten - ist das f\u00fcr euch vorstellbar?<\/strong><\/p><div id=\"polls-105-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li>F\u00fcr mich war das nie anders, dass ich, wenn es n\u00f6tig war, l\u00e4nger gearbeitet habe. <small>(29%, 16 Stimmen)<\/small><div class=\"wp-polls-bar\" aria-hidden=\"true\"><div class=\"wp-polls-bar-fill\" style=\"width: 29%;\"><\/div><\/div><\/li>\n\t\t<li>Als Unternehmer w\u00fcrde ich so eine Regeleung sehr begr\u00fc\u00dfen, das macht Sinn! <small>(29%, 16 Stimmen)<\/small><div class=\"wp-polls-bar\" aria-hidden=\"true\"><div class=\"wp-polls-bar-fill\" style=\"width: 29%;\"><\/div><\/div><\/li>\n\t\t<li>Ich sch\u00e4tze eine geregelte Arbeitswoche und stehe nicht auf \u00dcberstunden. <small>(18%, 10 Stimmen)<\/small><div class=\"wp-polls-bar\" aria-hidden=\"true\"><div class=\"wp-polls-bar-fill\" style=\"width: 18%;\"><\/div><\/div><\/li>\n\t\t<li>Die rosigen Zeiten sind f\u00fcr uns Arbeitnehmer ohnedies vorbei! <small>(15%, 8 Stimmen)<\/small><div class=\"wp-polls-bar\" aria-hidden=\"true\"><div class=\"wp-polls-bar-fill\" style=\"width: 15%;\"><\/div><\/div><\/li>\n\t\t<li>Hat wie alles Vor- und Nachteile! <small>(9%, 5 Stimmen)<\/small><div class=\"wp-polls-bar\" aria-hidden=\"true\"><div class=\"wp-polls-bar-fill\" style=\"width: 9%;\"><\/div><\/div><\/li>\n\t\t<\/ul><p style=\"text-align: center;\">Total Voters: <strong>55<\/strong><\/p><\/div>\n\t\t<input type=\"hidden\" id=\"poll_105_nonce\" name=\"wp-polls-nonce\" value=\"713d74074a\" \/>\n<\/div>\n<div id=\"polls-105-loading\" class=\"wp-polls wp-polls-loading\"><span class=\"wp-polls-spinner\" aria-hidden=\"true\"><\/span> Loading ...<\/div>\n<br \/>\nViel Arbeiten, wenn es viel zu tun gibt, weniger, wenn es weniger Auftr\u00e4ge gibt \u2013 das ist in vielen Branchen mit Kollektivvertrag nicht selbstverst\u00e4ndlich. Vor allem scheitert diese Vorgangsweise oft an der h\u00f6chst zul\u00e4ssigen Arbeitszeit an einem Tag. Dennoch gab es zuletzt Tendenzen an dieser \u201eHeiligen Kuh\u201c zu r\u00fctteln \u2013 nicht ohne heftige Diskussionen auszul\u00f6sen. Wir haben deshalb diese Frage im Bohneland zur Diskussion gestellt\u2026<\/p>\n<p>55 Votings wurden im Zeitraum abgegeben.<br \/>\n29 %, immerhin fast ein Drittel, gaben dabei an, ohnehin immer schon l\u00e4nger gearbeitet zu haben, wenn es n\u00f6tig war. Genausoviele w\u00fcrden als Unternehmer so eine Regelung unbedingt begr\u00fc\u00dfen. Weitere 18 % stehen auf eine geregelte Arbeitswoche. 15 % stellen fest, dass die rosigen Zeiten f\u00fcr Arbeitnehmer ohnehin vorbei w\u00e4ren. Und 9 % erkennen, dass es bei beiden Regelungen Vor- und Nachteile gibt.<\/p>\n<p>Ein Faktum ist: man muss heute in vielen Branchen sehr viel flexibler agieren als es der Kollektivvertrag verlangt und es gibt genug Arbeitnehmer, die schon lange ihr Arbeitspensum den Gegebenheiten anpassen mussten. Mit dem Vorteil des Zeitausgleich, wenn es mal ruhiger im B\u00fcro war\u2026  Um wettbewerbsf\u00e4hig zu bleiben im internationalen Vergleich ist eine derartige Flexibilit\u00e4t bestimmt im Kommen\u2026<\/p>\n<p>Vivienne<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viel Arbeiten, wenn es viel zu tun gibt, weniger, wenn es weniger Auftr&auml;ge gibt &ndash; das ist in vielen Branchen &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Flexiblere Arbeitszeiten &#8211; ist das f\u00fcr euch vorstellbar? &#8211; Umfrageeergebnis\" class=\"read-more button\" href=\"https:\/\/www.bohnenzeitung.com\/wp\/flexiblere-arbeitszeiten-ist-das-fuer-euch-vorstellbar-umfrageeergebnis\/#more-23003\" aria-label=\"Mehr Informationen \u00fcber Flexiblere Arbeitszeiten &#8211; ist das f\u00fcr euch vorstellbar? &#8211; Umfrageeergebnis\">Weiter<\/a><\/p>\n","protected":false},"author":6,"featured_media":28639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[87],"tags":[],"class_list":["post-23003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-umfrageergebnisse","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/23003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/comments?post=23003"}],"version-history":[{"count":0,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/23003\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media\/28639"}],"wp:attachment":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media?parent=23003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/categories?post=23003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/tags?post=23003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}