{"id":7380,"date":"2010-07-03T21:10:35","date_gmt":"2010-07-03T20:10:35","guid":{"rendered":"http:\/\/bohnenzeitung.com\/wp\/?p=7380"},"modified":"2010-07-03T21:10:35","modified_gmt":"2010-07-03T20:10:35","slug":"april-april","status":"publish","type":"post","link":"https:\/\/www.bohnenzeitung.com\/wp\/april-april\/","title":{"rendered":"April, April!"},"content":{"rendered":"<p>Feierabend&#8230;<\/p>\n<p>Ich mache es mir  bequem.<br \/>\nDie Katze auf dem Scho\u00df.<br \/>\nUnd lasse die Wolken vor\u00fcber ziehen.<br \/>\nAm abendlichen Himmel.<br \/>\nEs ist k\u00fchl.<br \/>\nAber ich bin frisch gebadet.<br \/>\nIch f\u00fchle mich gut.<br \/>\nApril, April!<br \/>\nVer\u00e4nderlich.<br \/>\nDie Sonne.<br \/>\nEben noch strahlt sie dich an.<br \/>\nUnd dann zerzaust dich der Wind.<br \/>\nUnd du fl\u00fcchtest vor dem Regen&#8230;<br \/>\nApril.<br \/>\nManche Menschen.<br \/>\nSie sind genauso.<br \/>\nUnberechenbar.<br \/>\nTrauen.<br \/>\nDarf man ihnen nicht.<br \/>\nMan k\u00f6nnte \u00fcberrascht werden.<br \/>\nB\u00f6se.<br \/>\nUnangenehm.<br \/>\nWer will das schon?<\/p>\n<p>Die Wolken werden  dichter.<br \/>\nDie Nacht f\u00e4llt ein.<br \/>\nIch seufze.<br \/>\nStrecke mich.<br \/>\nUnd g\u00e4hne ungeniert.<br \/>\nIch bin m\u00fcde.<br \/>\nBleiern m\u00fcde.<br \/>\nIch tr\u00e4ume schlecht.<br \/>\nSeit Wochen.<br \/>\nImmer wieder.<br \/>\nEs scheint.<br \/>\nAls ziehe mein Leben vorbei.<br \/>\nIn diesen Tr\u00e4umen.<br \/>\nEreignisse.<br \/>\nSie werden reflektiert.<br \/>\nRei\u00dfen Wunden auf.<br \/>\nUnd ich finde keine Ruhe.<br \/>\nObwohl ich schlafe&#8230;<br \/>\nUnd ich esse viel zu viel.<br \/>\nIch habe zugenommen.<br \/>\nEin Schutzpanzer.<br \/>\nUm das zu verarbeiten.<br \/>\nWas passiert ist.<br \/>\nUnd das schmerzt.<br \/>\nDas wird es noch l\u00e4nger&#8230;<\/p>\n<p>Die Katze.<br \/>\nSie putzt sich.<br \/>\nHat meinen Schreibtisch in Besitz genommen.<br \/>\nEinfach so&#8230;<br \/>\nIch beobachte sie.<br \/>\nW\u00e4hrend die Nacht.<br \/>\nSich \u00fcber die Stadt senkt.<br \/>\nSternenlos.<br \/>\nAuch der Mond.<br \/>\nHat sich versteckt.<br \/>\nHinter den Wolken.<br \/>\nUnd vielleicht regnet es.<br \/>\nIn der Nacht.<br \/>\nMag sein&#8230;<br \/>\nEs ist April<br \/>\nFreundschaft.<br \/>\nIst wie ein \u00dcberraschungspaket.<br \/>\nDas man \u00f6ffnet.<br \/>\nWenn man sich daf\u00fcr \u00f6ffnet.<br \/>\nAuf dem ersten Blick.<br \/>\nKann ein Pr\u00e4sent sch\u00f6n aussehen.<br \/>\nUnd gut.<br \/>\nAber der Eindruck.<br \/>\nEr vermag zu tr\u00fcgen.<br \/>\nUnd irgendwann.<br \/>\nWirft man es weg.<br \/>\nVoller Abscheu&#8230;<\/p>\n<p>Ich m\u00f6chte spazieren  gehen.<br \/>\nVerw\u00f6hnt von der Sonne.<br \/>\nMit einem L\u00e4cheln auf den Lippen&#8230;<br \/>\nAber l\u00e4cheln f\u00e4llt mir schwer.<br \/>\nUnd der Wind.<br \/>\nEr \u00fcberf\u00e4llt mich manchmal.<br \/>\nVon hinten.<br \/>\nUnerwartet.<br \/>\nUnd er zerw\u00fchlt nicht nur mein Haar.<br \/>\nEr w\u00fchlt auch meine Seele auf.<br \/>\nApril, April&#8230;<br \/>\nKein prachtvoller Fr\u00fchling.<br \/>\nTrotz des Vogelgezwitschers.<br \/>\nTrotz der bl\u00fchenden, gr\u00fcnenden Natur.<br \/>\nSchmerz.<br \/>\nUnsicherheit.<br \/>\nUnd eine Maske.<br \/>\nDie mich vor den anderen sch\u00fctzt.<br \/>\nUnd ihrem Stochern.<br \/>\nIn meinen Wunden.<br \/>\nIch narre sie alle!<br \/>\nApril, April!<\/p>\n<p>Vivienne\/Gedankensplitter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feierabend&hellip; Ich mache es mir bequem. Die Katze auf dem Scho&szlig;. Und lasse die Wolken vor&uuml;ber ziehen. Am abendlichen Himmel. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"April, April!\" class=\"read-more button\" href=\"https:\/\/www.bohnenzeitung.com\/wp\/april-april\/#more-7380\" aria-label=\"Mehr Informationen \u00fcber April, April!\">Weiter<\/a><\/p>\n","protected":false},"author":1,"featured_media":28639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-7380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gedankensplitter","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/7380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/comments?post=7380"}],"version-history":[{"count":0,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/7380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media\/28639"}],"wp:attachment":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media?parent=7380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/categories?post=7380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/tags?post=7380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}