{"id":8771,"date":"2010-12-21T15:33:01","date_gmt":"2010-12-21T14:33:01","guid":{"rendered":"http:\/\/bohnenzeitung.com\/wp\/?p=8771"},"modified":"2010-12-21T15:33:01","modified_gmt":"2010-12-21T14:33:01","slug":"vorbei-feuerlilie-5","status":"publish","type":"post","link":"https:\/\/www.bohnenzeitung.com\/wp\/vorbei-feuerlilie-5\/","title":{"rendered":"Vorbei &#8211; Gedankensplitter"},"content":{"rendered":"<p>Wieder eine kalte Nacht.<br \/>\nUnd deine Nase.<br \/>\nGanz zu.<br \/>\nSchnupfen.<br \/>\nNicht zu \u00e4ndern.<br \/>\nNoch eine Tasse Tee.<br \/>\nSch\u00f6n hei\u00df.<br \/>\nUnd China\u00f6l.<br \/>\nZum Inhalieren.<br \/>\nDas hilft.<br \/>\nUnd morgen.<br \/>\nDa ist ein anderer Tag.<br \/>\nEs wird schon&#8230;<br \/>\nDu legst dich hin.<br \/>\nD\u00f6st ein wenig.<br \/>\nUnd w\u00fcnscht dir.<br \/>\nDie Katze w\u00fcrde kommen.<br \/>\nDich w\u00e4rmen.<br \/>\nUnd dich umfangen.<br \/>\nMit all ihrer Liebe.<br \/>\nAber sie liegt im Bad.<br \/>\nAuf den Handt\u00fcchern.<br \/>\nSchon den ganzen Tag&#8230;<\/p>\n<p>Ein wenig Fieber.<br \/>\nUnd deine Gedanken.<br \/>\nVerwickelt.<br \/>\nEng&#8230;<br \/>\nDu denkst nach.<br \/>\n\u00dcber die letzten Wochen.<br \/>\n\u00dcber das letzte halbe Jahr.<br \/>\nSeltsam.<br \/>\nDass man immer bestimmt hat.<br \/>\n\u00dcber deinen Kopf.<br \/>\nHier und dort.<br \/>\nAndere.<br \/>\nDie durften widersprechen.<br \/>\nDu nicht.<br \/>\nDu wurdest erniedrigt.<br \/>\nGedem\u00fctigt.<br \/>\nNiedergemacht.<br \/>\nWenn du es wolltest.<br \/>\nOder man sagte.<br \/>\nVersuch es doch!<br \/>\nTrotzdem!<br \/>\nIrgendwie.<br \/>\nIst dir das zu bunt geworden.<br \/>\nWiderstand.<br \/>\nEr wurde zu deiner 2. Natur.<br \/>\nWenn du nicht wolltest.<br \/>\nNein.<br \/>\nKeine Diskussionen.<br \/>\nSchon auf Prinzip&#8230;<br \/>\nDu schn\u00e4uzt dich.<br \/>\nUnd wickelst den Schal.<br \/>\nEnger um deinen Hals.<br \/>\nEs muss besser werden!<br \/>\nOder?<\/p>\n<p>Dein Sch\u00e4del brummt.<br \/>\nWeil du nachdenkst.<br \/>\nWas sie jetzt wohl reden.<br \/>\n\u00dcber dich.<br \/>\nNichts Gutes.<br \/>\nWas auch sonst?<br \/>\nUnd die Dummdreiste.<br \/>\nDie immer redet davon.<br \/>\nWie jung sie nicht aussieht.<br \/>\nAnma\u00dfend und biestig.<br \/>\nKein Wunder.<br \/>\nDass sie 10 Jahre allein war.<br \/>\nUnd dazu sieht sie nicht j\u00fcnger aus.<br \/>\nAls sie ist&#8230;<br \/>\nKeinen Tag!<br \/>\nDie andere.<br \/>\nDie Hinterfotzige.<br \/>\nNeidig.<br \/>\nGierig.<br \/>\nEigentlich m\u00fcsste sie gr\u00fcn sein.<br \/>\nUm ihre Natur widerszuspiegeln.<br \/>\nGiftgr\u00fcn&#8230;<br \/>\nAm Ende noch er.<br \/>\nSelbstverliebt.<br \/>\nMr. Psycho-Spielchen.<br \/>\nSelbsternannter Alphamann.<br \/>\nUnd doch nur&#8230;<br \/>\nEin Schlappschwanz.<br \/>\nKlein und ergeben.<br \/>\nIn der obersten Chefetage.<br \/>\nGro\u00df.<br \/>\nWenn es um die Leute ging.<br \/>\nIn der eigenen Abteilung&#8230;<br \/>\nDir wird schlecht.<br \/>\nWenn du dran denkst&#8230;<br \/>\nVorbei.<br \/>\nSagt dir etwas.<br \/>\nVorbei&#8230;<br \/>\nIrgendwann.<br \/>\nWie das Fieber.<br \/>\nUnd der Schnupfen&#8230;<\/p>\n<p>Vivienne\/Gedankensplitter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wieder eine kalte Nacht. Und deine Nase. Ganz zu. Schnupfen. Nicht zu &auml;ndern. Noch eine Tasse Tee. Sch&ouml;n hei&szlig;. Und &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Vorbei &#8211; Gedankensplitter\" class=\"read-more button\" href=\"https:\/\/www.bohnenzeitung.com\/wp\/vorbei-feuerlilie-5\/#more-8771\" aria-label=\"Mehr Informationen \u00fcber Vorbei &#8211; Gedankensplitter\">Weiter<\/a><\/p>\n","protected":false},"author":1,"featured_media":28639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-8771","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gedankensplitter","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-50","resize-featured-image"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/8771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/comments?post=8771"}],"version-history":[{"count":0,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/posts\/8771\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media\/28639"}],"wp:attachment":[{"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/media?parent=8771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/categories?post=8771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bohnenzeitung.com\/wp\/wp-json\/wp\/v2\/tags?post=8771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}